{"id":761,"date":"2025-09-18T15:20:54","date_gmt":"2025-09-18T15:20:54","guid":{"rendered":"https:\/\/zalakaros.ap4.hu\/?post_type=latnivalo&#038;p=761"},"modified":"2025-10-21T14:12:41","modified_gmt":"2025-10-21T14:12:41","slug":"erdeszkilato","status":"publish","type":"latnivalo","link":"https:\/\/zalakaros.ap4.hu\/en\/latnivalo\/erdeszkilato\/","title":{"rendered":"Erd\u00e9szkil\u00e1t\u00f3"},"content":{"rendered":"","protected":false},"featured_media":762,"template":"","meta":{"_acf_changed":true},"categories":[52,53],"class_list":["post-761","latnivalo","type-latnivalo","status-publish","has-post-thumbnail","hentry","category-latnivalok","category-zalakarosi"],"acf":[],"_links":{"self":[{"href":"https:\/\/zalakaros.ap4.hu\/en\/wp-json\/wp\/v2\/latnivalo\/761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zalakaros.ap4.hu\/en\/wp-json\/wp\/v2\/latnivalo"}],"about":[{"href":"https:\/\/zalakaros.ap4.hu\/en\/wp-json\/wp\/v2\/types\/latnivalo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zalakaros.ap4.hu\/en\/wp-json\/wp\/v2\/media\/762"}],"wp:attachment":[{"href":"https:\/\/zalakaros.ap4.hu\/en\/wp-json\/wp\/v2\/media?parent=761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zalakaros.ap4.hu\/en\/wp-json\/wp\/v2\/categories?post=761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}